{"id":56633,"date":"2024-09-03T20:00:00","date_gmt":"2024-09-03T13:00:00","guid":{"rendered":"https:\/\/web.codi.or.th\/index.php\/?p=56633"},"modified":"2024-09-08T21:26:36","modified_gmt":"2024-09-08T14:26:36","slug":"%e0%b8%9e%e0%b8%ad%e0%b8%8a-%e0%b8%99%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b8%a1%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%99%e0%b8%b1%e0%b8%81%e0%b8%a7%e0%b8%b4%e0%b8%88%e0%b8%b1%e0%b8%a2%e0%b8%a5%e0%b8%87%e0%b8%9e","status":"publish","type":"post","link":"https:\/\/web.codi.or.th\/index.php\/20240903-56633\/","title":{"rendered":"\u0e1e\u0e2d\u0e0a.\u0e19\u0e33\u0e17\u0e35\u0e21\u0e19\u0e31\u0e01\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e25\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e15\u0e39\u0e25  \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22"},"content":{"rendered":"\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-1 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-1 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-1' class='dt-gallery-container gallery galleryid-56633 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20240903-56633\/1-514\/'><img width=\"800\" height=\"600\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/1-800x600.jpg\" class=\"attachment-large size-large\" alt=\"1\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/1-800x600.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/1-450x338.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/1-768x576.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/1.jpg 1477w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 30 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2567 \u00a0\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u00a0 \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e43\u0e15\u0e49\u00a0 \u0e08\u0e31\u0e14\u0e40\u0e27\u0e17\u0e35\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e19\u0e17\u0e19\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21 focus group \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e08\u0e31\u0e14\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23\u0e20\u0e32\u0e04\u0e35\u0e23\u0e48\u0e27\u0e21\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e48\u0e07\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e40\u0e02\u0e49\u0e21\u0e41\u0e02\u0e47\u0e07\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e15\u0e39\u0e25 \u0e13 \u0e2a\u0e21\u0e32\u0e04\u0e21\u0e0a\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e1a\u0e49\u0e32\u0e19\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e15\u0e39\u0e25\u00a0 \u0e21\u0e35\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e08\u0e33\u0e19\u0e27\u0e19 30 \u0e04\u0e19 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22\u0e41\u0e01\u0e19\u0e19\u0e33\u0e02\u0e1a\u0e27\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e07\u0e32\u0e19\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e15\u0e48\u0e32\u0e07 \u0e46 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e2d\u0e0a. \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e08\u0e32\u0e01 \u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22\u0e2a\u0e07\u0e02\u0e25\u0e32\u0e19\u0e04\u0e23\u0e34\u0e19\u0e17\u0e23\u0e4c \u0e27\u0e34\u0e17\u0e22\u0e32\u0e40\u0e02\u0e15\u0e1b\u0e31\u0e15\u0e15\u0e32\u0e19\u0e35<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-2 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-2 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-2 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-2' class='dt-gallery-container gallery galleryid-56633 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20240903-56633\/2-505\/'><img width=\"800\" height=\"600\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/2-1-800x600.jpg\" class=\"attachment-large size-large\" alt=\"2\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/2-1-800x600.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/2-1-450x338.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/2-1-768x576.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/2-1.jpg 1477w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>\u0e14\u0e23.\u0e27\u0e31\u0e19\u0e1e\u0e34\u0e0a\u0e34\u0e15\u00a0 \u0e28\u0e23\u0e35\u0e2a\u0e38\u0e02 \u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e41\u0e25\u0e30\u0e17\u0e35\u0e21 \u0e19\u0e33\u0e40\u0e2a\u0e19\u0e2d\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e08\u0e32\u0e01\u0e1c\u0e25\u0e01\u0e32\u0e23\u0e40\u0e01\u0e47\u0e1a\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01 \u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e25\u0e32\u0e22\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e34\u0e16\u0e38\u0e19\u0e32\u0e22\u0e19 2567\u00a0 \u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e08\u0e33\u0e19\u0e27\u0e19 30 \u0e04\u0e19 \u0e1e\u0e1a\u0e27\u0e48\u0e32 \u0e21\u0e35\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e2a\u0e20\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e27\u0e34\u0e2a\u0e32\u0e2b\u0e01\u0e34\u0e08\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e41\u0e25\u0e30\u0e01\u0e25\u0e38\u0e48\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e40\u0e0a\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19 \u0e40\u0e0a\u0e48\u0e19 \u0e17\u0e23\u0e31\u0e1e\u0e22\u0e32\u0e01\u0e23\u0e18\u0e23\u0e23\u0e21\u0e0a\u0e32\u0e15\u0e34 \u0e14\u0e49\u0e32\u0e19\u0e40\u0e14\u0e47\u0e01\u0e41\u0e25\u0e30\u0e40\u0e22\u0e32\u0e27\u0e0a\u0e19 \u0e14\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e14\u0e49\u0e32\u0e19\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e1c\u0e48\u0e32\u0e19\u0e01\u0e25\u0e44\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22 2 \u0e2a\u0e48\u0e27\u0e19 \u0e04\u0e37\u0e2d \u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e20\u0e32\u0e22\u0e43\u0e19 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e1c\u0e39\u0e49\u0e19\u0e33\u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e28\u0e31\u0e01\u0e22\u0e20\u0e32\u0e1e\u0e2a\u0e39\u0e07\u00a0 \u0e1b\u0e31\u0e08\u0e08\u0e31\u0e22\u0e20\u0e32\u0e22\u0e19\u0e2d\u0e01 \u0e44\u0e14\u0e49\u0e41\u0e01\u0e48 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e23\u0e31\u0e10 \u0e2b\u0e19\u0e48\u0e27\u0e22\u0e07\u0e32\u0e19\u0e40\u0e2d\u0e01\u0e0a\u0e19 \u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e20\u0e32\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e15\u0e48\u0e32\u0e07 \u0e46<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-3 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-3 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-3 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-3' class='dt-gallery-container gallery galleryid-56633 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20240903-56633\/3-491\/'><img width=\"800\" height=\"600\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/3-1-800x600.jpg\" class=\"attachment-large size-large\" alt=\"3\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/3-1-800x600.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/3-1-450x338.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/3-1-768x576.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/3-1.jpg 1477w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>\u0e08\u0e36\u0e07\u0e19\u0e33\u0e21\u0e32\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e25\u0e44\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22\u0e41\u0e1a\u0e1a\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e1c\u0e39\u0e49\u0e43\u0e2b\u0e49\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e20\u0e32\u0e29\u0e13\u0e4c\u0e40\u0e0a\u0e34\u0e07\u0e25\u0e36\u0e01 30 \u0e04\u0e19 \u0e21\u0e38\u0e48\u0e07\u0e40\u0e1b\u0e49\u0e32\u0e44\u0e1b\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19 \u201c \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19\u201d \u00a0\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e08\u0e36\u0e07\u0e44\u0e14\u0e49\u0e19\u0e33\u0e21\u0e32\u0e2b\u0e32\u0e23\u0e37\u0e2d\u0e43\u0e19\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 \u00a0\u00a0\u0e41\u0e25\u0e30\u0e2b\u0e32\u0e01\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e43\u0e14\u0e17\u0e35\u0e48\u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e22\u0e49\u0e07\u0e44\u0e14\u0e49\u0e17\u0e31\u0e19\u0e17\u0e35 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19 \u0e17\u0e35\u0e48\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e44\u0e14\u0e49\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e2d\u0e32\u0e17\u0e34 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e15\u0e31\u0e49\u0e07\u0e2a\u0e21\u0e32\u0e04\u0e21\u0e0a\u0e32\u0e27\u0e1b\u0e23\u0e30\u0e21\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e1a\u0e49\u0e32\u0e19\u00a0 \u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e07\u0e32\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u00a0 \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u00a0 \u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07 \u201c\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e25\u0e32\u0e07\u201d \u0e2b\u0e23\u0e37\u0e2d \u201c\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e40\u0e08\u0e23\u0e08\u0e32\u0e41\u0e25\u0e30\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e2b\u0e32\u0e23\u0e37\u0e2d\u201d \u00a0\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e44\u0e14\u0e49\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e25\u0e32\u0e07 \u201c\u0e23\u0e31\u0e01\u0e08\u0e31\u0e07\u0e2a\u0e15\u0e39\u0e25\u201d \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e07\u0e32\u0e19 \u0e40\u0e27\u0e17\u0e35\u0e2a\u0e21\u0e31\u0e0a\u0e0a\u0e32\u0e04\u0e19\u0e2a\u0e15\u0e39\u0e25 \u0e04\u0e23\u0e31\u0e49\u0e07\u0e17\u0e35\u0e48 11 \u00a0\u201c\u0e1e\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e2a\u0e15\u0e39\u0e25\u0e15\u0e37\u0e48\u0e19\u0e23\u0e39\u0e49 \u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e2d\u0e38\u0e17\u0e22\u0e32\u0e19\u0e18\u0e23\u0e13\u0e35\u0e42\u0e25\u0e01 \u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e15\u0e19\u0e40\u0e2d\u0e07\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e31\u0e48\u0e07\u0e22\u0e37\u0e19\u201d \u0e43\u0e19\u0e27\u0e31\u0e19\u0e23\u0e38\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19 31 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2567\u0e13 \u0e2a\u0e27\u0e19\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e30\u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e15\u0e33\u0e1a\u0e01\u0e33\u0e41\u0e1e\u0e07 \u0e2d.\u0e25\u0e30\u0e07\u0e39 \u0e08.\u0e2a\u0e15\u0e39\u0e25<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-4 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-4 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-4 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-4 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-4' class='dt-gallery-container gallery galleryid-56633 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20240903-56633\/4-470\/'><img width=\"800\" height=\"600\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/4-1-800x600.jpg\" class=\"attachment-large size-large\" alt=\"4\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/4-1-800x600.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/4-1-450x338.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/4-1-768x576.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/09\/4-1.jpg 1477w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>\u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e01\u0e32\u0e23\u0e08\u0e30\u0e2b\u0e32\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e25\u0e44\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22\u0e41\u0e1a\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e2a\u0e15\u0e39\u0e25 \u0e2b\u0e32\u0e01\u0e08\u0e30\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e43\u0e14\u0e1b\u0e23\u0e30\u0e40\u0e14\u0e47\u0e19\u0e2b\u0e19\u0e36\u0e48\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e41\u0e25\u0e01\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48 \u0e2a\u0e19\u0e43\u0e08\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e01\u0e25\u0e32\u0e07 \u0e25\u0e33\u0e14\u0e31\u0e1a\u0e23\u0e2d\u0e07\u0e25\u0e07\u0e21\u0e32 \u0e04\u0e37\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e0b\u0e36\u0e48\u0e07\u0e21\u0e32\u0e01\u0e01\u0e27\u0e48\u0e32\u0e01\u0e2d\u0e07\u0e17\u0e38\u0e19\u0e2a\u0e27\u0e31\u0e2a\u0e14\u0e34\u0e01\u0e32\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e15\u0e33\u0e1a\u0e25 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e04\u0e19\u0e17\u0e38\u0e01\u0e01\u0e25\u0e38\u0e48\u0e21\u0e27\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e20\u0e31\u0e22\u0e1e\u0e34\u0e1a\u0e31\u0e15\u0e34\u00a0 \u0e23\u0e30\u0e1a\u0e1a\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e \u0e1a\u0e49\u0e32\u0e19\u0e1e\u0e2d\u0e40\u0e1e\u0e35\u0e22\u0e07 \u0e01\u0e32\u0e23\u0e04\u0e38\u0e49\u0e21\u0e04\u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e42\u0e20\u0e04 \u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19<\/p>\n<p>\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e08\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e02\u0e49\u0e2d\u0e2a\u0e23\u0e38\u0e1b\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e40\u0e27\u0e17\u0e35\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u00a0 \u0e40\u0e1a\u0e37\u0e49\u0e2d\u0e07\u0e15\u0e49\u0e19\u0e19\u0e31\u0e01\u0e27\u0e34\u0e08\u0e31\u0e22\u0e08\u0e30\u0e19\u0e33\u0e1a\u0e17\u0e2a\u0e19\u0e17\u0e19\u0e32\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e17\u0e19\u0e32\u0e01\u0e25\u0e38\u0e48\u0e21\u0e43\u0e19\u0e04\u0e23\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e44\u0e1b\u0e08\u0e31\u0e14\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c \u0e40\u0e23\u0e35\u0e22\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e07 \u0e22\u0e01\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e25\u0e44\u0e01\u0e20\u0e32\u0e04\u0e35\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e38\u0e01\u0e0a\u0e48\u0e27\u0e07\u0e27\u0e31\u0e22\u0e41\u0e1a\u0e1a\u0e1a\u0e39\u0e23\u0e13\u0e32\u0e01\u0e32\u0e23 \u0e2b\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e15\u0e34\u0e21\u0e08\u0e30\u0e44\u0e14\u0e49\u0e1b\u0e23\u0e30\u0e2a\u0e32\u0e19\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e2d\u0e35\u0e01\u0e04\u0e23\u0e31\u0e49\u0e07<\/p>\n<p style=\"text-align: right\">\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e2a\u0e37\u0e48\u0e2d\u0e2a\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 30 \u0e2a\u0e34\u0e07\u0e2b\u0e32\u0e04\u0e21 2567 \u00a0\u0e17\u0e35\u0e48\u0e1c\u0e48\u0e32\u0e19\u0e21\u0e32 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e04\u0e27&hellip;<\/p>\n","protected":false},"author":19,"featured_media":56634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[35,123],"tags":[],"class_list":{"0":"post-56633","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-development-news","8":"category-123","9":"category-35","11":"description-off"},"_links":{"self":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/56633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/comments?post=56633"}],"version-history":[{"count":4,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/56633\/revisions"}],"predecessor-version":[{"id":56740,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/56633\/revisions\/56740"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media\/56634"}],"wp:attachment":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media?parent=56633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/categories?post=56633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/tags?post=56633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}