{"id":45352,"date":"2023-05-09T16:29:27","date_gmt":"2023-05-09T09:29:27","guid":{"rendered":"https:\/\/web.codi.or.th\/index.php\/?p=45352"},"modified":"2023-05-09T16:29:27","modified_gmt":"2023-05-09T09:29:27","slug":"%e0%b9%80%e0%b8%a3%e0%b8%b7%e0%b9%88%e0%b8%ad%e0%b8%87%e0%b8%94%e0%b8%b5%e0%b8%94%e0%b8%b5%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%8a%e0%b8%b8%e0%b8%a1%e0%b8%8a%e0%b8%99-%e0%b8%95%e0%b8%ad%e0%b8%99-1100","status":"publish","type":"post","link":"https:\/\/web.codi.or.th\/index.php\/20230509-45352\/","title":{"rendered":"\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e35\u0e14\u0e35\u0e17\u0e35\u0e48\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e15\u0e2d\u0e19\u0e17\u0e35\u0e48 2136 : \u0e1e\u0e2d\u0e0a.\u0e08\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e23\u0e16\u0e44\u0e1f\u0e2f \u0e41\u0e25\u0e30\u0e20\u0e32\u0e04\u0e35 \u0e2b\u0e19\u0e38\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e23\u0e34\u0e21\u0e23\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e2d\u0e35\u0e2a\u0e32\u0e19 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07"},"content":{"rendered":"\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-1 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-1 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-1' class='dt-gallery-container gallery galleryid-45352 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230509-45352\/345255768_1393921101340647_2528896438919483603_n\/'><img width=\"800\" height=\"449\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n-800x449.jpg\" class=\"attachment-large size-large\" alt=\"345255768 1393921101340647 2528896438919483603 N\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n-800x449.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n-450x253.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n-768x431.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n-1536x863.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p><em><strong>\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\/<\/strong><\/em> \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9-10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2566 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e42\u0e14\u0e22\u0e07\u0e32\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e23\u0e34\u0e21\u0e23\u0e32\u0e07 (\u0e1e\u0e17\u0e23.) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e41\u0e25\u0e30\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e08\u0e31\u0e14\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2b\u0e19\u0e38\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e23\u0e34\u0e21\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e13 \u0e2b\u0e2d\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e22\u0e2d\u0e14\u0e02\u0e27\u0e31\u0e0d\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e28\u0e34\u0e25\u0e32 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e28\u0e34\u0e25\u0e32 \u0e2d.\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e08.\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e40\u0e08\u0e15\u0e19\u0e32 \u0e27\u0e38\u0e12\u0e34\u0e0d\u0e32\u0e13 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e34\u0e191 (\u0e01\u0e32\u0e23\u0e23\u0e16\u0e44\u0e1f\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2a\u0e31\u0e07\u0e04\u0e21\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e02\u0e2d\u0e07\u0e21\u0e19\u0e38\u0e29\u0e22\u0e4c\u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e28\u0e34\u0e25\u0e32 \u0e40\u0e17\u0e28\u0e1a\u0e32\u0e25\u0e19\u0e04\u0e23\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e01\u0e1b.\u0e2d\u0e1e\u0e0a.\u0e20\u0e32\u0e04\u0e2d\u0e35\u0e2a\u0e32\u0e19 \u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e2a\u0e25\u0e31\u0e21 4 \u0e20\u0e32\u0e04 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e04\u0e19\u0e44\u0e23\u0e49\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e23\u0e34\u0e21\u0e23\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e22\u0e48\u0e32\u0e42\u0e21 \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e20\u0e32\u0e04\u0e2d\u0e35\u0e2a\u0e32\u0e19 \u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e1e\u0e2d\u0e0a. \u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-2 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-2 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-2 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-2' class='dt-gallery-container gallery galleryid-45352 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230509-45352\/345891904_1233171970904575_2386310892794655630_n\/'><img width=\"800\" height=\"450\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345891904_1233171970904575_2386310892794655630_n-800x450.jpg\" class=\"attachment-large size-large\" alt=\"345891904 1233171970904575 2386310892794655630 N\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345891904_1233171970904575_2386310892794655630_n-800x450.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345891904_1233171970904575_2386310892794655630_n-450x253.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345891904_1233171970904575_2386310892794655630_n-768x432.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345891904_1233171970904575_2386310892794655630_n.jpg 960w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>\u0e19\u0e32\u0e22\u0e2a\u0e22\u0e32\u0e21 \u0e19\u0e19\u0e17\u0e4c\u0e04\u0e33\u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c \u0e1c\u0e39\u0e49\u0e0a\u0e48\u0e27\u0e22\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e20\u0e32\u0e04 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e15\u0e34\u0e14\u0e15\u0e32\u0e21\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e04\u0e21\u0e19\u0e32\u0e04\u0e21\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e16\u0e44\u0e1f\u0e23\u0e32\u0e07\u0e04\u0e39\u0e48 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e16\u0e44\u0e1f\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e08\u0e23\u0e34\u0e0d\u0e02\u0e2d\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07 \u0e41\u0e15\u0e48\u0e21\u0e35\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a \u0e42\u0e14\u0e22\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e2f \u0e21\u0e35\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e01\u0e31\u0e1a\u0e1c\u0e39\u0e49\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e07 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e14\u0e35\u0e02\u0e36\u0e49\u0e19\u0e01\u0e27\u0e48\u0e32\u0e40\u0e01\u0e48\u0e32 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e32\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27 \u0e23\u0e31\u0e1a\u0e23\u0e39\u0e49\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c \u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e21\u0e37\u0e2d\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e44\u0e1b\u0e02\u0e49\u0e32\u0e07\u0e2b\u0e19\u0e49\u0e32\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32\u0e40\u0e01\u0e48\u0e32 \u0e43\u0e2b\u0e49\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e27\u0e32\u0e14\u0e1c\u0e27\u0e32\u0e16\u0e39\u0e01\u0e44\u0e25\u0e48\u0e23\u0e37\u0e49\u0e2d\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e40\u0e23\u0e32\u0e08\u0e30\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e2b\u0e32\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e01\u0e43\u0e2b\u0e49\u0e14\u0e35\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14 \u0e43\u0e2b\u0e49\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e19\u0e49\u0e2d\u0e22\u0e17\u0e35\u0e48\u0e2a\u0e38\u0e14<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-3 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-3 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-3 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-3' class='dt-gallery-container gallery galleryid-45352 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230509-45352\/345255768_1393921101340647_2528896438919483603_n\/'><img width=\"800\" height=\"449\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n-800x449.jpg\" class=\"attachment-large size-large\" alt=\"345255768 1393921101340647 2528896438919483603 N\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n-800x449.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n-450x253.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n-768x431.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n-1536x863.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345255768_1393921101340647_2528896438919483603_n.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>\u0e0b\u0e36\u0e48\u0e07\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e44\u0e14\u0e49\u0e40\u0e2b\u0e47\u0e19\u0e0a\u0e2d\u0e1a \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e07\u0e32\u0e19\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e07 \u0e23\u0e30\u0e22\u0e30 5 \u0e1b\u0e35 (2566-2571) \u0e27\u0e07\u0e40\u0e07\u0e34\u0e19\u0e23\u0e27\u0e21 7,718.94 \u0e25\u0e49\u0e32\u0e19\u0e1a\u0e32\u0e17 \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e01\u0e25\u0e38\u0e48\u0e21\u0e40\u0e1b\u0e49\u0e32\u0e2b\u0e21\u0e32\u0e22 35 \u0e08\u0e31\u0e07\u0e2b\u0e27\u0e31\u0e14 300 \u0e0a\u0e38\u0e21\u0e0a\u0e19 27,084 \u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e42\u0e14\u0e22\u0e21\u0e35\u0e2b\u0e25\u0e31\u0e01\u0e01\u0e32\u0e23\u0e2a\u0e33\u0e04\u0e31\u0e0d 3 \u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 1) \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e08\u0e49\u0e32\u0e02\u0e2d\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e21\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c \u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e01\u0e32\u0e23\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15 2) \u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e1a\u0e1a \u0e04\u0e23\u0e2d\u0e1a\u0e04\u0e25\u0e38\u0e21\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e17\u0e31\u0e49\u0e07\u0e2b\u0e21\u0e14 \u0e41\u0e25\u0e303) \u0e21\u0e35\u0e23\u0e30\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e41\u0e25\u0e30\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e23\u0e48\u0e27\u0e21\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19 \u0e20\u0e32\u0e04\u0e35 \u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e25\u0e44\u0e01\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e43\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e17\u0e49\u0e2d\u0e07\u0e16\u0e34\u0e48\u0e19<\/p>\n<p>\u0e19\u0e32\u0e22\u0e40\u0e08\u0e15\u0e19\u0e32 \u0e27\u0e38\u0e12\u0e34\u0e0d\u0e32\u0e13 \u0e15\u0e33\u0e41\u0e2b\u0e19\u0e48\u0e07 \u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e34\u0e191 (\u0e01\u0e32\u0e23\u0e23\u0e16\u0e44\u0e1f\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22) \u0e01\u0e25\u0e48\u0e32\u0e27\u0e16\u0e36\u0e07 \u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e41\u0e19\u0e27\u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e41\u0e25\u0e30\u0e41\u0e1c\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e07\u0e2b\u0e23\u0e37\u0e2d\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e01\u0e32\u0e23\u0e23\u0e16\u0e44\u0e1f\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e42\u0e14\u0e22\u0e23\u0e30\u0e1a\u0e38\u0e27\u0e48\u0e32 \u0e19\u0e42\u0e22\u0e1a\u0e32\u0e22\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e07\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e21\u0e35\u0e2d\u0e22\u0e39\u0e48 3 \u0e23\u0e30\u0e1a\u0e1a \u0e04\u0e37\u0e2d \u0e23\u0e16\u0e44\u0e1f\u0e17\u0e32\u0e07\u0e04\u0e39\u0e48 \u0e17\u0e35\u0e48\u0e40\u0e2a\u0e19\u0e2d\u0e42\u0e14\u0e22\u0e01\u0e32\u0e23\u0e23\u0e16\u0e44\u0e1f\u0e41\u0e2b\u0e48\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e44\u0e17\u0e22 \u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e35\u0e48 2 \u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e16\u0e44\u0e1f\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25 \u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e17\u0e32\u0e07\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e07\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e41\u0e25\u0e30\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48 3 \u0e04\u0e37\u0e2d \u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e16\u0e44\u0e1f\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e2a\u0e19\u0e32\u0e21\u0e1a\u0e34\u0e19<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-4 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-4 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-4 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-4 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-4' class='dt-gallery-container gallery galleryid-45352 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230509-45352\/345887662_193551193572540_3823971599170881607_n\/'><img width=\"800\" height=\"449\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345887662_193551193572540_3823971599170881607_n-800x449.jpg\" class=\"attachment-large size-large\" alt=\"345887662 193551193572540 3823971599170881607 N\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345887662_193551193572540_3823971599170881607_n-800x449.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345887662_193551193572540_3823971599170881607_n-450x253.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345887662_193551193572540_3823971599170881607_n-768x431.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345887662_193551193572540_3823971599170881607_n-1536x863.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/345887662_193551193572540_3823971599170881607_n.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>\u0e43\u0e19\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e07 \u0e08\u0e30\u0e21\u0e35\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e15\u0e32\u0e21\u0e41\u0e19\u0e27\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23 \u0e40\u0e27\u0e19\u0e04\u0e37\u0e19 \u0e17\u0e35\u0e48\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e04\u0e48\u0e2d\u0e19\u0e02\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e31\u0e01\u0e43\u0e08\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e49\u0e07\u0e01\u0e31\u0e1a\u0e0a\u0e32\u0e27\u0e1a\u0e49\u0e32\u0e19\u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e01\u0e32\u0e23\u0e16\u0e39\u0e01\u0e40\u0e27\u0e19\u0e04\u0e37\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2b\u0e19\u0e31\u0e01\u0e2b\u0e19\u0e32 \u0e2a\u0e30\u0e40\u0e17\u0e37\u0e2d\u0e19\u0e43\u0e08 \u0e41\u0e15\u0e48\u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e21\u0e35\u0e42\u0e2d\u0e01\u0e32\u0e2a\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e43\u0e2b\u0e49\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07<\/p>\n<p>\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23\u0e28\u0e39\u0e19\u0e22\u0e4c\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e01\u0e23\u0e23\u0e21\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e4c\u0e17\u0e35\u0e48\u0e14\u0e34\u0e191 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e15\u0e48\u0e2d\u0e27\u0e48\u0e32 \u0e42\u0e14\u0e22\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e23\u0e16\u0e44\u0e1f\u0e23\u0e30\u0e1a\u0e1a\u0e17\u0e32\u0e07\u0e04\u0e39\u0e48\u0e43\u0e19\u0e1b\u0e31\u0e08\u0e08\u0e38\u0e1a\u0e31\u0e19 \u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e44\u0e14\u0e49\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e40\u0e2a\u0e23\u0e47\u0e08\u0e41\u0e25\u0e49\u0e27 \u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e01\u0e33\u0e25\u0e31\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e1a\u0e32\u0e07\u0e2a\u0e48\u0e27\u0e19\u0e27\u0e48\u0e32\u0e08\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e0b\u0e36\u0e48\u0e07\u0e02\u0e36\u0e49\u0e19\u0e01\u0e31\u0e1a\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32 \u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07\u0e43\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e20\u0e32\u0e04\u0e2d\u0e35\u0e2a\u0e32\u0e19 \u0e17\u0e35\u0e48\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e2d\u0e38\u0e14\u0e23\u0e18\u0e32\u0e19\u0e35 \u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e08\u0e30\u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u0e40\u0e27\u0e35\u0e22\u0e15\u0e19\u0e32\u0e21\u0e2a\u0e39\u0e48\u0e08\u0e35\u0e19 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e02\u0e19\u0e2a\u0e48\u0e07\u0e2a\u0e34\u0e19\u0e04\u0e49\u0e32\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e02\u0e13\u0e30\u0e19\u0e35\u0e49\u0e2d\u0e22\u0e39\u0e48\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e40\u0e2a\u0e19\u0e2d\u0e04\u0e13\u0e30\u0e23\u0e31\u0e10\u0e21\u0e19\u0e15\u0e23\u0e35\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e1e\u0e34\u0e08\u0e32\u0e23\u0e13\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e1b\u0e35 2566 \u0e04\u0e07\u0e08\u0e30\u0e44\u0e21\u0e48\u0e44\u0e14\u0e49\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07 \u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07\u0e1b\u0e35 2567 \u0e43\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e16\u0e44\u0e1f\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e47\u0e27\u0e2a\u0e39\u0e07 \u0e0b\u0e36\u0e48\u0e07\u0e21\u0e35\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e48\u0e27\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e23\u0e48\u0e07\u0e14\u0e48\u0e27\u0e19\u0e04\u0e37\u0e2d\u0e40\u0e2a\u0e49\u0e19\u0e17\u0e32\u0e07 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e2f-\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u0e0b\u0e36\u0e48\u0e07\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e41\u0e25\u0e49\u0e27 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e44\u0e2b\u0e23\u0e48\u0e17\u0e35\u0e48\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e21\u0e32\u0e08\u0e48\u0e2d\u0e2b\u0e19\u0e49\u0e32\u0e1a\u0e49\u0e32\u0e19 \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e40\u0e2a\u0e49\u0e19\u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32-\u0e2b\u0e19\u0e2d\u0e07\u0e04\u0e32\u0e22 \u0e1b\u0e31\u0e01\u0e2b\u0e21\u0e38\u0e14\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e01\u0e25\u0e32\u0e07\u0e1b\u0e35 2567 \u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e01\u0e48\u0e2d\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 5 \u0e1b\u0e35 \u0e16\u0e49\u0e32\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e16\u0e44\u0e1f\u0e17\u0e38\u0e01\u0e17\u0e48\u0e32\u0e19\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e43\u0e08\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e32\u0e21\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e17\u0e35\u0e48\u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e43\u0e2b\u0e49\u0e40\u0e07\u0e34\u0e19\u0e0a\u0e48\u0e27\u0e22\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e40\u0e22\u0e35\u0e22\u0e27\u0e22\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07 \u0e21\u0e35\u0e01\u0e32\u0e23\u0e08\u0e31\u0e14\u0e23\u0e39\u0e1b\u0e08\u0e31\u0e14\u0e41\u0e1b\u0e25\u0e07\u0e27\u0e32\u0e07\u0e1c\u0e31\u0e07\u0e17\u0e35\u0e48\u0e14\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a\u0e40\u0e23\u0e35\u0e22\u0e1a\u0e23\u0e49\u0e2d\u0e22<\/p>\n<p>\u0e40\u0e23\u0e32\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e15\u0e34\u0e1a\u0e42\u0e15\u0e08\u0e32\u0e01\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e07 \u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e08\u0e30\u0e17\u0e33\u0e17\u0e33\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e2b\u0e25\u0e32\u0e19 \u0e01\u0e32\u0e23\u0e23\u0e16\u0e44\u0e1f\u0e2f \u0e01\u0e47\u0e08\u0e31\u0e14\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e43\u0e2b\u0e49 \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e01\u0e47\u0e43\u0e2b\u0e49\u0e01\u0e32\u0e23\u0e2a\u0e19\u0e31\u0e1a\u0e2a\u0e19\u0e38\u0e19\u0e1c\u0e48\u0e32\u0e19 \u0e1e\u0e2d\u0e0a. \u0e41\u0e15\u0e48\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e0a\u0e38\u0e21\u0e0a\u0e19 \u0e04\u0e27\u0e23\u0e40\u0e1b\u0e47\u0e19\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e21\u0e35\u0e23\u0e30\u0e22\u0e30\u0e01\u0e32\u0e23\u0e23\u0e48\u0e19\u0e15\u0e32\u0e21\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e0b\u0e36\u0e48\u0e07\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e2a\u0e2d\u0e07\u0e02\u0e49\u0e32\u0e07\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f \u0e15\u0e48\u0e2d\u0e44\u0e1b\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15 \u0e08\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e31\u0e49\u0e07\u0e01\u0e32\u0e23\u0e02\u0e22\u0e32\u0e22\u0e15\u0e31\u0e27\u0e17\u0e32\u0e07\u0e40\u0e28\u0e23\u0e29\u0e10\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e08\u0e30\u0e40\u0e2d\u0e37\u0e49\u0e2d\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e17\u0e33\u0e21\u0e32\u0e2b\u0e32\u0e01\u0e34\u0e19\u0e02\u0e2d\u0e07\u0e25\u0e39\u0e01\u0e2b\u0e25\u0e32\u0e19 \u0e0b\u0e36\u0e48\u0e07\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e17\u0e35\u0e48 \u0e1e\u0e2d\u0e0a. \u0e40\u0e2a\u0e19\u0e2d \u0e23\u0e31\u0e10\u0e1a\u0e32\u0e25\u0e21\u0e2d\u0e07\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e47\u0e19\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e17\u0e35\u0e48\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e2a\u0e21\u0e04\u0e27\u0e23\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e39\u0e41\u0e25\u0e1c\u0e39\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e01\u0e23\u0e30\u0e17\u0e1a \u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e16\u0e44\u0e1f\u0e2f \u0e43\u0e2b\u0e49\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27 30 \u0e1b\u0e35 \u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e44\u0e2b\u0e19\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e19\u0e2b\u0e32\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48\u0e23\u0e2d\u0e07\u0e23\u0e31\u0e1a\u0e17\u0e35\u0e48\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e15\u0e48\u0e2d\u0e44\u0e1b \u0e0b\u0e36\u0e48\u0e07\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 1 \u0e1b\u0e35 \u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e23\u0e32\u0e22\u0e0a\u0e37\u0e48\u0e2d\u0e04\u0e23\u0e31\u0e27\u0e40\u0e23\u0e37\u0e2d\u0e19 \u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21 \u0e41\u0e25\u0e30\u0e02\u0e2d\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e22\u0e37\u0e48\u0e19\u0e43\u0e2b\u0e49\u0e17\u0e31\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30 5 \u0e1b\u0e35 \u0e44\u0e21\u0e48\u0e40\u0e01\u0e34\u0e19\u0e1b\u0e35 2571<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-5 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-5 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-5 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-5 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-5' class='dt-gallery-container gallery galleryid-45352 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230509-45352\/344820277_636963301626241_8465118369582906529_n\/'><img width=\"800\" height=\"450\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/344820277_636963301626241_8465118369582906529_n-800x450.jpg\" class=\"attachment-large size-large\" alt=\"344820277 636963301626241 8465118369582906529 N\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/344820277_636963301626241_8465118369582906529_n-800x450.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/344820277_636963301626241_8465118369582906529_n-450x253.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/344820277_636963301626241_8465118369582906529_n-768x432.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/05\/344820277_636963301626241_8465118369582906529_n.jpg 960w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e31\u0e21\u0e21\u0e19\u0e32\u0e2f \u0e44\u0e14\u0e49\u0e21\u0e35\u0e01\u0e32\u0e23\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e48\u0e32\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e16\u0e44\u0e1f\u0e2f \u0e08\u0e32\u0e01\u0e1e\u0e35\u0e48\u0e19\u0e49\u0e2d\u0e07\u0e0a\u0e38\u0e21\u0e0a\u0e19\u0e23\u0e34\u0e21\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e2f \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e23\u0e34\u0e21\u0e23\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e22\u0e48\u0e32\u0e42\u0e21 \u0e19\u0e04\u0e23\u0e23\u0e32\u0e0a\u0e2a\u0e35\u0e21\u0e32 \u0e42\u0e14\u0e22 \u0e1c\u0e39\u0e49\u0e41\u0e17\u0e19\u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e23\u0e34\u0e21\u0e23\u0e32\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e22\u0e48\u0e32\u0e42\u0e21\/ \u0e40\u0e04\u0e23\u0e37\u0e2d\u0e02\u0e48\u0e32\u0e22\u0e1f\u0e37\u0e49\u0e19\u0e1f\u0e39\u0e1b\u0e23\u0e30\u0e0a\u0e32\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e2a\u0e23\u0e23\u0e04\u0e4c \u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e31\u0e10 \u0e17\u0e35\u0e48\u0e14\u0e34\u0e19\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e39\u0e48\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e01\u0e23\u0e30\u0e1a\u0e27\u0e19\u0e01\u0e32\u0e23\u0e40\u0e0a\u0e48\u0e32\u0e17\u0e35\u0e48\u0e14\u0e34\u0e19 \u0e43\u0e19\u0e01\u0e32\u0e23\u0e41\u0e01\u0e49\u0e44\u0e02\u0e1b\u0e31\u0e0d\u0e2b\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e42\u0e14\u0e22\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e21\u0e39\u0e25\u0e19\u0e34\u0e18\u0e34\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e22\u0e31\u0e07\u0e21\u0e35\u0e01\u0e32\u0e23\u0e40\u0e2a\u0e19\u0e2d\u0e41\u0e19\u0e27\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e2b\u0e19\u0e38\u0e19\u0e40\u0e2a\u0e23\u0e34\u0e21\u0e01\u0e32\u0e23\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22\u0e23\u0e34\u0e21\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e20\u0e32\u0e04\u0e15\u0e30\u0e27\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e40\u0e09\u0e35\u0e22\u0e07\u0e40\u0e2b\u0e19\u0e37\u0e2d \u0e42\u0e14\u0e22\u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e41\u0e25\u0e30\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1a\u0e48\u0e07\u0e01\u0e25\u0e38\u0e48\u0e21\u0e22\u0e48\u0e2d\u0e22 \u0e23\u0e30\u0e14\u0e31\u0e1a\u0e40\u0e21\u0e37\u0e2d\u0e07 6 \u0e01\u0e25\u0e38\u0e48\u0e21 \u0e17\u0e1a\u0e17\u0e27\u0e19\u0e2a\u0e16\u0e32\u0e19\u0e13\u0e4c\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e1c\u0e39\u0e49\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e08\u0e32\u0e01\u0e23\u0e30\u0e1a\u0e1a\u0e23\u0e32\u0e07 \u0e23\u0e27\u0e21\u0e17\u0e31\u0e49\u0e07\u0e27\u0e32\u0e07\u0e41\u0e1c\u0e19\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e01\u0e32\u0e23\u0e02\u0e31\u0e1a\u0e40\u0e04\u0e25\u0e37\u0e48\u0e2d\u0e19\u0e01\u0e32\u0e23\u0e17\u0e33\u0e07\u0e32\u0e19\u0e23\u0e30\u0e14\u0e31\u0e1a\u0e1e\u0e37\u0e49\u0e19\u0e17\u0e35\u0e48 \u0e23\u0e30\u0e22\u0e30 5 \u0e1b\u0e35 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e21\u0e31\u0e48\u0e19\u0e04\u0e07\u0e43\u0e19\u0e17\u0e35\u0e48\u0e2d\u0e22\u0e39\u0e48\u0e2d\u0e32\u0e28\u0e31\u0e22 \u0e21\u0e35\u0e04\u0e38\u0e13\u0e20\u0e32\u0e1e\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e17\u0e35\u0e48\u0e14\u0e35\u0e15\u0e48\u0e2d\u0e44\u0e1b<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e02\u0e2d\u0e19\u0e41\u0e01\u0e48\u0e19\/ \u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e27\u0e31\u0e19\u0e17\u0e35\u0e48 9-10 \u0e1e\u0e24\u0e29\u0e20\u0e32\u0e04\u0e21 2566 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04&hellip;<\/p>\n","protected":false},"author":3,"featured_media":45356,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[31,106,120,29],"tags":[],"class_list":{"0":"post-45352","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-self-governance","8":"category-thailand-getting-better","9":"category-120","10":"category-accommodation-security","11":"category-31","12":"category-106","14":"category-29","15":"description-off"},"_links":{"self":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/45352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/comments?post=45352"}],"version-history":[{"count":1,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/45352\/revisions"}],"predecessor-version":[{"id":45358,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/45352\/revisions\/45358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media\/45356"}],"wp:attachment":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media?parent=45352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/categories?post=45352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/tags?post=45352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}