{"id":44220,"date":"2023-03-24T16:55:46","date_gmt":"2023-03-24T09:55:46","guid":{"rendered":"https:\/\/web.codi.or.th\/index.php\/?p=44220"},"modified":"2023-03-24T16:58:33","modified_gmt":"2023-03-24T09:58:33","slug":"%e0%b8%9e%e0%b8%ad%e0%b8%8a-%e0%b8%88%e0%b8%b1%e0%b8%94%e0%b8%ad%e0%b8%9a%e0%b8%a3%e0%b8%a1-%e0%b9%82%e0%b8%84%e0%b8%a3%e0%b8%87%e0%b8%81%e0%b8%b2%e0%b8%a3-%e0%b8%ad%e0%b8%9a%e0%b8%a3","status":"publish","type":"post","link":"https:\/\/web.codi.or.th\/index.php\/20230324-44220\/","title":{"rendered":"\u0e1e\u0e2d\u0e0a. \u0e08\u0e31\u0e14\u0e2d\u0e1a\u0e23\u0e21 \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2d\u0e1a\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2d\u0e1e\u0e22\u0e1e\u0e2b\u0e19\u0e35\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2566\u201d"},"content":{"rendered":"\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-1 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-1 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-1 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-1' class='dt-gallery-container gallery galleryid-44220 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/1-1-4\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1.1-800x533.jpg\" class=\"attachment-large size-large\" alt=\"1.1\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1.1-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1.1-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1.1-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1.1-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1.1-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1.1.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p><strong>\u0e1e\u0e2d\u0e0a. \/<\/strong> \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 24 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2566 \u0e40\u0e27\u0e25\u0e32 09.30 \u0e19. \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e44\u0e1e\u0e1a\u0e39\u0e25\u0e22\u0e4c \u0e27\u0e31\u0e12\u0e19\u0e28\u0e34\u0e23\u0e34\u0e18\u0e23\u0e23\u0e21 \u0e0a\u0e31\u0e49\u0e19 1 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19(\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07 \u0e2a\u0e16\u0e32\u0e1a\u0e31\u0e19\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23\u0e0a\u0e38\u0e21\u0e0a\u0e19 (\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e32\u0e23\u0e21\u0e2b\u0e32\u0e0a\u0e19) \u0e23\u0e48\u0e27\u0e21\u0e01\u0e31\u0e1a\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e2b\u0e31\u0e27\u0e2b\u0e21\u0e32\u0e01 \u0e08\u0e31\u0e14 <strong>\u201c\u0e2d\u0e1a\u0e23\u0e21<\/strong><strong>\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2d\u0e1e\u0e22\u0e1e\u0e2b\u0e19\u0e35\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.<\/strong><strong>2566\u201d<\/strong><\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-2 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-2 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-2 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-2 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-2' class='dt-gallery-container gallery galleryid-44220 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/3-278\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/3-23-800x533.jpg\" class=\"attachment-large size-large\" alt=\"3\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/3-23-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/3-23-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/3-23-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/3-23-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/3-23-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/3-23.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p style=\"text-align: center\"><em><span style=\"font-size: 10pt;color: #800080\">\u0e19\u0e32\u0e22\u0e18\u0e19\u0e31\u0e0a \u0e19\u0e24\u0e1e\u0e23\u0e1e\u0e07\u0e29\u0e4c \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23<\/span><\/em><\/p>\n<p>\u0e42\u0e14\u0e22\u0e21\u0e35\u0e19\u0e32\u0e22\u0e18\u0e19\u0e31\u0e0a \u0e19\u0e24\u0e1e\u0e23\u0e1e\u0e07\u0e29\u0e4c \u0e23\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e2d\u0e33\u0e19\u0e27\u0e22\u0e01\u0e32\u0e23 \u0e40\u0e1b\u0e47\u0e19\u0e1b\u0e23\u0e30\u0e18\u0e32\u0e19\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e1b\u0e34\u0e14 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e1e\u0e2d\u0e0a. \u0e42\u0e14\u0e22\u0e19\u0e32\u0e07\u0e2a\u0e32\u0e27\u0e1a\u0e31\u0e27\u0e17\u0e2d\u0e07 \u0e08\u0e31\u0e19\u0e17\u0e23\u0e4c\u0e40\u0e2b\u0e25\u0e37\u0e2d\u0e07 \u0e2b\u0e31\u0e27\u0e2b\u0e19\u0e49\u0e32\u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e07\u0e32\u0e19\u0e01\u0e25\u0e32\u0e07 \u0e01\u0e25\u0e48\u0e32\u0e27\u0e23\u0e32\u0e22\u0e07\u0e32\u0e19\u0e27\u0e31\u0e15\u0e16\u0e38\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c \u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23 \u201c\u0e2d\u0e1a\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e01\u0e32\u0e23\u0e2d\u0e1e\u0e22\u0e1e\u0e2b\u0e19\u0e35\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e1c\u0e0a\u0e34\u0e0d\u0e2a\u0e16\u0e32\u0e19\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e1b\u0e23\u0e30\u0e08\u0e33\u0e1b\u0e35\u0e07\u0e1a\u0e1b\u0e23\u0e30\u0e21\u0e32\u0e13 \u0e1e.\u0e28.2566 \u0e08\u0e31\u0e14\u0e02\u0e36\u0e49\u0e19\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e41\u0e1c\u0e19\u0e01\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a \u0e41\u0e25\u0e30\u0e21\u0e32\u0e15\u0e23\u0e01\u0e32\u0e23\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e23\u0e30\u0e07\u0e31\u0e1a\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22 \u0e21\u0e35\u0e17\u0e31\u0e01\u0e29\u0e30\u0e43\u0e19\u0e01\u0e32\u0e23\u0e43\u0e0a\u0e49\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07 \u0e01\u0e32\u0e23\u0e40\u0e2d\u0e32\u0e15\u0e31\u0e27\u0e23\u0e2d\u0e14\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e44\u0e1f\u0e44\u0e2b\u0e21\u0e49 \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e17\u0e31\u0e49\u0e07\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e1a\u0e17\u0e1a\u0e32\u0e17\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e01\u0e33\u0e2b\u0e19\u0e14\u0e43\u0e19\u0e41\u0e1c\u0e19\u0e23\u0e30\u0e07\u0e31\u0e1a\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22\u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2d\u0e1e\u0e22\u0e1e\u0e2b\u0e19\u0e35\u0e44\u0e1f\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e44\u0e2b\u0e21\u0e49\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e1b\u0e25\u0e2d\u0e14\u0e20\u0e31\u0e22 \u0e41\u0e25\u0e30\u0e2a\u0e23\u0e49\u0e32\u0e07\u0e17\u0e31\u0e28\u0e19\u0e04\u0e15\u0e34\u0e17\u0e35\u0e48\u0e14\u0e35\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e21\u0e35\u0e2a\u0e48\u0e27\u0e19\u0e23\u0e48\u0e27\u0e21\u0e43\u0e19\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e25\u0e14\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e48\u0e22\u0e07\u0e15\u0e48\u0e2d\u0e01\u0e32\u0e23\u0e40\u0e01\u0e34\u0e14\u0e2d\u0e31\u0e04\u0e04\u0e35\u0e20\u0e31\u0e22\u0e41\u0e25\u0e30\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e39\u0e0d\u0e40\u0e2a\u0e35\u0e22\u0e15\u0e48\u0e2d\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e41\u0e25\u0e30\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e20\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e07\u0e04\u0e4c\u0e01\u0e23<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-3 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-3 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-3 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-3 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-3' class='dt-gallery-container gallery galleryid-44220 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7500\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7500-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7500\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7500-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7500-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7500-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7500-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7500-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7500.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>\u0e15\u0e48\u0e2d\u0e21\u0e32\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 13.00 \u2013 14.00 \u0e19. \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23 \u201c\u0e2d\u0e1a\u0e23\u0e21\u0e01\u0e32\u0e23\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e04\u0e27\u0e32\u0e21\u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e32\u0e19 IT \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19\u201d \u0e27\u0e31\u0e15\u0e16\u0e38\u0e02\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e2a\u0e07\u0e04\u0e4c\u0e02\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e04\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e40\u0e15\u0e23\u0e35\u0e22\u0e21\u0e15\u0e31\u0e27\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e23\u0e31\u0e01\u0e29\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25\u0e17\u0e32\u0e07 IT \u0e41\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e02\u0e2d\u0e07\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e2d\u0e34\u0e40\u0e25\u0e47\u0e01\u0e17\u0e23\u0e2d\u0e19\u0e34\u0e01\u0e2a\u0e4c\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14\u0e27\u0e48\u0e32\u0e08\u0e30\u0e04\u0e27\u0e1a\u0e04\u0e38\u0e21\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e01\u0e34\u0e14\u0e40\u0e2b\u0e15\u0e38\u0e09\u0e38\u0e01\u0e40\u0e09\u0e34\u0e19 \u0e42\u0e14\u0e22\u0e19\u0e32\u0e22\u0e40\u0e1f\u0e32\u0e0b\u0e35 \u0e40\u0e08\u0e4a\u0e30\u0e40\u0e15\u0e4a\u0e30 \u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e40\u0e17\u0e04\u0e42\u0e19\u0e42\u0e25\u0e22\u0e35\u0e2a\u0e32\u0e23\u0e2a\u0e19\u0e40\u0e17\u0e28\u0e2d\u0e32\u0e27\u0e38\u0e42\u0e2a \u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e01\u0e48\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-4 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-4 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-4 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-4 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-4' class='dt-gallery-container gallery galleryid-44220 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7650\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7650-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7650\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7650-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7650-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7650-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7650-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7650-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7650.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>\u0e41\u0e25\u0e30\u0e43\u0e19\u0e0a\u0e48\u0e27\u0e07 14.00 \u2013 16.30 \u0e19. \u0e40\u0e1b\u0e47\u0e19\u0e01\u0e32\u0e23\u0e1d\u0e36\u0e01\u0e20\u0e32\u0e04\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u00a0 \u201c\u0e01\u0e32\u0e23\u0e2d\u0e1e\u0e22\u0e1e\u0e2b\u0e19\u0e35\u0e44\u0e1f\u0e41\u0e25\u0e30\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e14\u0e49\u0e27\u0e22\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e0a\u0e19\u0e34\u0e14\u0e21\u0e37\u0e2d\u0e16\u0e37\u0e2d \u0e2a\u0e32\u0e22\u0e09\u0e35\u0e14\u0e19\u0e49\u0e33\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e25\u0e30\u0e2d\u0e38\u0e1b\u0e01\u0e23\u0e13\u0e4c\u0e01\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e43\u0e19\u0e2d\u0e32\u0e04\u0e32\u0e23\u201d \u0e42\u0e14\u0e22\u0e21\u0e35 \u0e19\u0e32\u0e22\u0e01\u0e34\u0e15\u0e15\u0e34\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e1e\u0e07\u0e28\u0e4c\u0e01\u0e21\u0e25\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e40\u0e08\u0e49\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e20\u0e31\u0e22 \u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e25\u0e30\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22\u0e2b\u0e31\u0e27\u0e2b\u0e21\u0e32\u0e01 \u0e01\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e25\u0e30\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22 4 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e20\u0e31\u0e22 \u0e01\u0e23\u0e38\u0e07\u0e40\u0e17\u0e1e\u0e21\u0e2b\u0e32\u0e19\u0e04\u0e23 \u0e41\u0e25\u0e30\u0e17\u0e35\u0e21\u0e07\u0e32\u0e19 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e34\u0e17\u0e22\u0e32\u0e01\u0e23\u0e43\u0e19\u0e01\u0e32\u0e23\u0e2d\u0e1a\u0e23\u0e21\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e0b\u0e36\u0e48\u0e07\u0e42\u0e04\u0e23\u0e07\u0e01\u0e32\u0e23\u0e14\u0e31\u0e07\u0e01\u0e25\u0e48\u0e32\u0e27 \u0e21\u0e35\u0e1c\u0e39\u0e49\u0e40\u0e02\u0e49\u0e32\u0e2d\u0e1a\u0e23\u0e21 \u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e14\u0e49\u0e27\u0e22 \u0e1c\u0e39\u0e49\u0e1a\u0e23\u0e34\u0e2b\u0e32\u0e23\u0e41\u0e25\u0e30\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48 \u0e1e\u0e2d\u0e0a. \u0e43\u0e19\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e1f\u0e31\u0e07\u0e1a\u0e23\u0e23\u0e22\u0e32\u0e22\u0e17\u0e24\u0e29\u0e0e\u0e35 \u0e08\u0e33\u0e19\u0e27\u0e19\u0e01\u0e27\u0e48\u0e32 50 \u0e04\u0e19 \u0e17\u0e31\u0e49\u0e07\u0e43\u0e19\u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21\u0e41\u0e25\u0e30\u0e23\u0e30\u0e1a\u0e1a\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c Zoom Meeting \u0e41\u0e25\u0e30\u0e0a\u0e48\u0e27\u0e07\u0e1d\u0e36\u0e01\u0e0b\u0e49\u0e2d\u0e21\u0e2d\u0e1e\u0e22\u0e1e \u0e08\u0e33\u0e19\u0e27\u0e19 50 \u0e04\u0e19<\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-5 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-5 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 50%;\n\t\t\t\t}\n\t\t\t\t#gallery-5 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-5 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-5' class='dt-gallery-container gallery galleryid-44220 gallery-columns-2 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7637\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7637-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7637\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7637-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7637-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7637-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7637-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7637-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7637.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7635\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7635-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7635\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7635-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7635-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7635-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7635-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7635-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7635.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-6 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-6 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 50%;\n\t\t\t\t}\n\t\t\t\t#gallery-6 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-6 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-6' class='dt-gallery-container gallery galleryid-44220 gallery-columns-2 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4-264\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4-23-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4-23-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4-23-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4-23-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4-23-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4-23-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4-23.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/2-290\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/2-22-800x533.jpg\" class=\"attachment-large size-large\" alt=\"2\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/2-22-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/2-22-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/2-22-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/2-22-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/2-22-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/2-22.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p style=\"text-align: center\"><em><span style=\"font-size: 10pt;color: #800080\">\u0e19\u0e32\u0e22\u0e01\u0e34\u0e15\u0e15\u0e34\u0e28\u0e31\u0e01\u0e14\u0e34\u0e4c \u0e1e\u0e07\u0e28\u0e4c\u0e01\u0e21\u0e25\u0e23\u0e31\u0e15\u0e19\u0e4c \u0e40\u0e08\u0e49\u0e32\u0e1e\u0e19\u0e31\u0e01\u0e07\u0e32\u0e19\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e20\u0e31\u0e22 \u0e0a\u0e33\u0e19\u0e32\u0e0d\u0e01\u0e32\u0e23\u0e2a\u0e16\u0e32\u0e19\u0e35\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e25\u0e30\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22\u0e2b\u0e31\u0e27\u0e2b\u0e21\u0e32\u0e01 \u0e01\u0e2d\u0e07\u0e1b\u0e0f\u0e34\u0e1a\u0e31\u0e15\u0e34\u0e01\u0e32\u0e23\u0e14\u0e31\u0e1a\u0e40\u0e1e\u0e25\u0e34\u0e07\u0e41\u0e25\u0e30\u0e01\u0e39\u0e49\u0e20\u0e31\u0e22 4 \u0e2a\u0e33\u0e19\u0e31\u0e01\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e41\u0e25\u0e30\u0e1a\u0e23\u0e23\u0e40\u0e17\u0e32\u0e2a\u0e32\u0e18\u0e32\u0e23\u0e13\u0e20\u0e31\u0e22<\/span><\/em><\/p>\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-7 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-7 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-7 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-7 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-7' class='dt-gallery-container gallery galleryid-44220 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/1-293\/'><img width=\"800\" height=\"541\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1-23-800x541.jpg\" class=\"attachment-large size-large\" alt=\"1\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1-23-800x541.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1-23-450x304.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1-23-768x519.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1-23-1536x1039.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1-23.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-8 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-8 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 50%;\n\t\t\t\t}\n\t\t\t\t#gallery-8 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-8 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-8' class='dt-gallery-container gallery galleryid-44220 gallery-columns-2 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/7-200\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/7-22-800x533.jpg\" class=\"attachment-large size-large\" alt=\"7\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/7-22-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/7-22-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/7-22-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/7-22-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/7-22-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/7-22.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/6-235\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/6-23-800x533.jpg\" class=\"attachment-large size-large\" alt=\"6\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/6-23-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/6-23-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/6-23-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/6-23-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/6-23-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/6-23.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-9 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-9 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 33%;\n\t\t\t\t}\n\t\t\t\t#gallery-9 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-9 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-9' class='dt-gallery-container gallery galleryid-44220 gallery-columns-3 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7534\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7534-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7534\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7534-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7534-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7534-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7534-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7534-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7534.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7542\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7542-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7542\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7542-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7542-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7542-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7542-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7542-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7542.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7528\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7528-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7528\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7528-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7528-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7528-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7528-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7528-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7528.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-10 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-10 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 33%;\n\t\t\t\t}\n\t\t\t\t#gallery-10 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-10 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-10' class='dt-gallery-container gallery galleryid-44220 gallery-columns-3 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7589\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7589-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7589\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7589-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7589-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7589-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7589-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7589-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7589.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7590\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7590-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7590\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7590-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7590-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7590-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7590-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7590-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7590.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7600\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7600-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7600\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7600-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7600-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7600-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7600-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7600-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7600.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-11 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-11 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 50%;\n\t\t\t\t}\n\t\t\t\t#gallery-11 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-11 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-11' class='dt-gallery-container gallery galleryid-44220 gallery-columns-2 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7620\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7620-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7620\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7620-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7620-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7620-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7620-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7620-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7620.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/4a8a7628\/'><img width=\"800\" height=\"533\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7628-800x533.jpg\" class=\"attachment-large size-large\" alt=\"4a8a7628\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7628-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7628-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7628-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7628-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7628-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/4A8A7628.jpg 2024w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n\n\t\t\t<style type='text\/css'>\n\t\t\t\t#gallery-12 {\n\t\t\t\t\tmargin: auto;\n\t\t\t\t}\n\t\t\t\t#gallery-12 .gallery-item {\n\t\t\t\t\tfloat: left;\n\t\t\t\t\tmargin-top: 10px;\n\t\t\t\t\ttext-align: center;\n\t\t\t\t\twidth: 100%;\n\t\t\t\t}\n\t\t\t\t#gallery-12 img {\n\t\t\t\t\tborder: 2px solid #cfcfcf;\n\t\t\t\t}\n\t\t\t\t#gallery-12 .gallery-caption {\n\t\t\t\t\tmargin-left: 0;\n\t\t\t\t}\n\t\t\t\t\/* see gallery_shortcode() in wp-includes\/media.php *\/\n\t\t\t<\/style>\n\t\t<div id='gallery-12' class='dt-gallery-container gallery galleryid-44220 gallery-columns-1 gallery-size-large'><dl class='gallery-item'>\n\t\t\t\t<dt class='gallery-icon landscape'>\n\t\t\t\t\t<a class=\"rollover\" href='https:\/\/web.codi.or.th\/index.php\/20230324-44220\/attachment\/1678602191406\/'><img width=\"617\" height=\"306\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1678602191406.jpg\" class=\"attachment-large size-large\" alt=\"1678602191406\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1678602191406.jpg 617w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/03\/1678602191406-450x223.jpg 450w\" sizes=\"(max-width: 617px) 100vw, 617px\" \/><\/a>\n\t\t\t\t<\/dt><\/dl><br style=\"clear: both\" \/>\n\t\t\t<\/div>\n\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e1e\u0e2d\u0e0a. \/ \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49 24 \u0e21\u0e35\u0e19\u0e32\u0e04\u0e21 2566 \u0e40\u0e27\u0e25\u0e32 09.30 \u0e19. \u0e13 \u0e2b\u0e49\u0e2d\u0e07\u0e1b\u0e23\u0e30\u0e0a\u0e38\u0e21&hellip;<\/p>\n","protected":false},"author":19,"featured_media":891,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false},"categories":[35,49,106],"tags":[],"class_list":["post-44220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-development-news","category-announcement","category-thailand-getting-better","category-35","category-49","category-106","description-off"],"_links":{"self":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/44220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/comments?post=44220"}],"version-history":[{"count":3,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/44220\/revisions"}],"predecessor-version":[{"id":44247,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/44220\/revisions\/44247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media\/891"}],"wp:attachment":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media?parent=44220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/categories?post=44220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/tags?post=44220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}