{"id":53891,"date":"2024-05-15T17:45:00","date_gmt":"2024-05-15T10:45:00","guid":{"rendered":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21.jpg"},"modified":"2024-05-15T17:45:00","modified_gmt":"2024-05-15T10:45:00","slug":"%e0%b8%82%e0%b8%a2%e0%b8%b0%e0%b8%ad%e0%b8%ad%e0%b8%a1","status":"inherit","type":"attachment","link":"https:\/\/web.codi.or.th\/index.php\/20240515-53889\/%e0%b8%82%e0%b8%a2%e0%b8%b0%e0%b8%ad%e0%b8%ad%e0%b8%a1\/","title":{"rendered":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"class_list":["post-53891","attachment","type-attachment","status-inherit","hentry","description-off"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21.jpg'><img width=\"450\" height=\"253\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-450x253.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-450x253.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-800x450.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-768x432.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-1536x864.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21.jpg 1706w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1706,"height":960,"file":"2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21.jpg","filesize":326154,"sizes":{"medium":{"file":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-450x253.jpg","width":450,"height":253,"filesize":39486,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-450x253.jpg"},"large":{"file":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-800x450.jpg","width":800,"height":450,"filesize":108825,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-800x450.jpg"},"thumbnail":{"file":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-150x150.jpg","width":150,"height":150,"filesize":9416,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-150x150.jpg"},"medium_large":{"file":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-768x432.jpg","width":768,"height":432,"filesize":100727,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-768x432.jpg"},"thumblist":{"file":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-300x300.jpg","width":300,"height":300,"filesize":32560,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-300x300.jpg"},"meccarouselthumb":{"file":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-474x324.jpg","width":474,"height":324,"filesize":50005,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-474x324.jpg"},"gridsquare":{"file":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-391x260.jpg","width":391,"height":260,"filesize":34715,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-391x260.jpg"},"tileview":{"file":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-300x400.jpg","width":300,"height":400,"filesize":40407,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-300x400.jpg"},"1536x1536":{"file":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-1536x864.jpg","width":1536,"height":864,"filesize":314933,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21-1536x864.jpg"},"full":{"file":"\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21.jpg","width":1706,"height":960,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":53889,"source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2024\/05\/\u0e02\u0e22\u0e30\u0e2d\u0e2d\u0e21.jpg","_links":{"self":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media\/53891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/users\/3"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":53889,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/53889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}