{"id":46888,"date":"2023-07-25T10:11:26","date_gmt":"2023-07-25T03:11:26","guid":{"rendered":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19.jpg"},"modified":"2023-07-25T10:11:26","modified_gmt":"2023-07-25T03:11:26","slug":"%e0%b8%95-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b9%81%e0%b8%97%e0%b9%88%e0%b8%99","status":"inherit","type":"attachment","link":"https:\/\/web.codi.or.th\/index.php\/20230725-46886\/%e0%b8%95-%e0%b8%9e%e0%b8%a3%e0%b8%b0%e0%b9%81%e0%b8%97%e0%b9%88%e0%b8%99\/","title":{"rendered":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19"},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"class_list":["post-46888","attachment","type-attachment","status-inherit","hentry","description-off"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19.jpg'><img width=\"450\" height=\"300\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-450x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-450x300.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-800x533.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-768x512.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-391x260.jpg 391w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-1536x1024.jpg 1536w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19.jpg 2024w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2024,"height":1349,"file":"2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19.jpg","filesize":282073,"sizes":{"medium":{"file":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-450x300.jpg","width":450,"height":300,"filesize":32258,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-450x300.jpg"},"large":{"file":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-800x533.jpg","width":800,"height":533,"filesize":75323,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-800x533.jpg"},"thumbnail":{"file":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-150x150.jpg","width":150,"height":150,"filesize":7612,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-150x150.jpg"},"medium_large":{"file":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-768x512.jpg","width":768,"height":512,"filesize":70658,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-768x512.jpg"},"thumblist":{"file":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-300x300.jpg","width":300,"height":300,"filesize":21534,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-300x300.jpg"},"meccarouselthumb":{"file":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-474x324.jpg","width":474,"height":324,"filesize":35125,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-474x324.jpg"},"gridsquare":{"file":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-391x260.jpg","width":391,"height":260,"filesize":25969,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-391x260.jpg"},"tileview":{"file":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-300x400.jpg","width":300,"height":400,"filesize":25203,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-300x400.jpg"},"1536x1536":{"file":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-1536x1024.jpg","width":1536,"height":1024,"filesize":188040,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19-1536x1024.jpg"},"full":{"file":"\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19.jpg","width":2024,"height":1349,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":46886,"source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/07\/\u0e15.\u0e1e\u0e23\u0e30\u0e41\u0e17\u0e48\u0e19.jpg","_links":{"self":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media\/46888","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/users\/3"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":46886,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/46886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}