{"id":42738,"date":"2023-02-10T16:02:09","date_gmt":"2023-02-10T09:02:09","guid":{"rendered":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2.jpg"},"modified":"2023-02-10T16:02:09","modified_gmt":"2023-02-10T09:02:09","slug":"line_album_10266_%e0%b9%92%e0%b9%93%e0%b9%90%e0%b9%92%e0%b9%91%e0%b9%90_2","status":"inherit","type":"attachment","link":"https:\/\/web.codi.or.th\/index.php\/20230210-42737\/line_album_10266_%e0%b9%92%e0%b9%93%e0%b9%90%e0%b9%92%e0%b9%91%e0%b9%90_2\/","title":{"rendered":"LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2"},"author":19,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false},"class_list":["post-42738","attachment","type-attachment","status-inherit","hentry","description-off"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2.jpg'><img width=\"450\" height=\"337\" src=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-450x337.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-450x337.jpg 450w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-800x600.jpg 800w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-768x576.jpg 768w, https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2.jpg 1478w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1478,"height":1108,"file":"2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2.jpg","filesize":355926,"sizes":{"medium":{"file":"LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-450x337.jpg","width":450,"height":337,"filesize":40258,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-450x337.jpg"},"large":{"file":"LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-800x600.jpg","width":800,"height":600,"filesize":95691,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-800x600.jpg"},"thumbnail":{"file":"LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-150x150.jpg","width":150,"height":150,"filesize":8282,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-150x150.jpg"},"medium_large":{"file":"LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-768x576.jpg","width":768,"height":576,"filesize":90009,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-768x576.jpg"},"thumblist":{"file":"LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-300x300.jpg","width":300,"height":300,"filesize":24912,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-300x300.jpg"},"meccarouselthumb":{"file":"LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-474x324.jpg","width":474,"height":324,"filesize":40751,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-474x324.jpg"},"gridsquare":{"file":"LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-391x260.jpg","width":391,"height":260,"filesize":29286,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-391x260.jpg"},"tileview":{"file":"LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-300x400.jpg","width":300,"height":400,"filesize":29469,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2-300x400.jpg"},"full":{"file":"LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2.jpg","width":1478,"height":1108,"mime_type":"image\/jpeg","source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":42737,"source_url":"https:\/\/web.codi.or.th\/wp-content\/uploads\/2023\/02\/LINE_ALBUM_10266_\u0e52\u0e53\u0e50\u0e52\u0e51\u0e50_2.jpg","_links":{"self":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media\/42738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/users\/19"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":42737,"href":"https:\/\/web.codi.or.th\/index.php\/wp-json\/wp\/v2\/posts\/42737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}